{"id":15843,"date":"2023-10-11T12:21:15","date_gmt":"2023-10-11T12:21:15","guid":{"rendered":"https:\/\/www.staging.proveca.com\/?page_id=15843"},"modified":"2026-05-14T08:51:16","modified_gmt":"2026-05-14T08:51:16","slug":"healthcare-professionals","status":"publish","type":"page","link":"https:\/\/www.proveca.com\/ga\/healthcare-professionals\/","title":{"rendered":"Healthcare Professionals"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7qc8ed7-97755ffaa3dd6ffa34ebf58ccb1bba9a\">\n.avia-section.av-k7qc8ed7-97755ffaa3dd6ffa34ebf58ccb1bba9a{\nbackground-color:#ecf2f6;\nbackground-image:url(https:\/\/www.proveca.com\/wp-content\/uploads\/2023\/09\/big-leaf-4.png);\nbackground-repeat:no-repeat;\nbackground-position:50% 50%;\nbackground-attachment:scroll;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-k7qc8ed7-97755ffaa3dd6ffa34ebf58ccb1bba9a main_color avia-section-default avia-no-border-styling  avia-builder-el-0  el_before_av_section  avia-builder-el-first  avia-full-stretch avia-bg-style-scroll av-minimum-height av-minimum-height-custom av-height-custom  container_wrap fullsize'  data-section-bg-repeat='stretch' data-av_minimum_height_px='150'><div class='container av-section-cont-open' style='height:150px'><main  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-15843'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7up14rm-309c1687c14d2441696c0c2ebc6945a5\">\n.flex_column.av-k7up14rm-309c1687c14d2441696c0c2ebc6945a5{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-k7up14rm-309c1687c14d2441696c0c2ebc6945a5 av_one_full  avia-builder-el-1  avia-builder-el-no-sibling  first flex_column_div av-animated-generic left-to-right av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k80eskyx-d5446999b794e8de3c28d3c9e3f59db5\">\n#top .av-special-heading.av-k80eskyx-d5446999b794e8de3c28d3c9e3f59db5{\npadding-bottom:10px;\ncolor:#ffffff;\n}\nbody .av-special-heading.av-k80eskyx-d5446999b794e8de3c28d3c9e3f59db5 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-k80eskyx-d5446999b794e8de3c28d3c9e3f59db5 .special-heading-inner-border{\nborder-color:#ffffff;\n}\n.av-special-heading.av-k80eskyx-d5446999b794e8de3c28d3c9e3f59db5 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-k80eskyx-d5446999b794e8de3c28d3c9e3f59db5 av-special-heading-h1 custom-color-heading blockquote modern-quote  avia-builder-el-2  avia-builder-el-no-sibling '><h1 class='av-special-heading-tag '  >Healthcare Professionals<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><\/div>\n\n<\/div><\/div><\/main><!-- close content main element --><\/div><\/div><div id='av_section_2'  class='avia-section av-ba49y2-7acfa1d8ed06a1989be0f7d47126d79f main_color avia-section-default avia-no-border-styling  avia-builder-el-3  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-15843'><div class='entry-content-wrapper clearfix'>\n<div  class='flex_column av-67c18j-b7865ee58b08e203de45328e0451ccb2 av_two_third  avia-builder-el-4  el_before_av_one_third  avia-builder-el-first  first flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3app7l-7d7b963f2fdca1be6bcd0900c8bd3b33\">\n#top .av-special-heading.av-3app7l-7d7b963f2fdca1be6bcd0900c8bd3b33{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-3app7l-7d7b963f2fdca1be6bcd0900c8bd3b33 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-3app7l-7d7b963f2fdca1be6bcd0900c8bd3b33 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-3app7l-7d7b963f2fdca1be6bcd0900c8bd3b33 av-special-heading-h2  avia-builder-el-5  el_before_av_textblock  avia-builder-el-first '><h2 class='av-special-heading-tag '  >Proveca medicines for children<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-mkmljdhr-491004a9806f5a7290dc59260daf7e12 '  ><div class='avia_textblock' ><p>This section is intended for Healthcare Professionals in the Republic of Ireland only and contains promotional content.<\/p>\n<\/div><\/section><\/p><\/div><div  class='flex_column av-1b54g3n-0ec395e296d354337e28f9bdf14b984f av_one_third  avia-builder-el-7  el_after_av_two_third  el_before_av_one_third  uk_hcp_side_menu flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-lxes09m6-787fd8ff40517c00bf69456acd181b17\">\n.avia-image-container.av-lxes09m6-787fd8ff40517c00bf69456acd181b17 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-lxes09m6-787fd8ff40517c00bf69456acd181b17 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-lxes09m6-787fd8ff40517c00bf69456acd181b17 av-styling- avia-align-center  avia-builder-el-8  el_before_av_sidebar  avia-builder-el-first '  ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image- avia-img-lazy-loading-not- avia_image ' src=\"https:\/\/www.staging.proveca.com\/wp-content\/uploads\/2024\/06\/child_teddy_bear.webp\" alt='' title=''   \/><\/div><\/div><\/div><br \/>\n<div  class='avia-builder-widget-area clearfix  avia-builder-el-9  el_after_av_image  avia-builder-el-last '><div id=\"nav_menu-8\" class=\"widget clearfix widget_nav_menu\"><div class=\"menu-ir-hcp-sub-menu-container\"><ul id=\"menu-ir-hcp-sub-menu\" class=\"menu\"><li id=\"menu-item-17233\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17233\"><a href=\"https:\/\/www.proveca.com\/ga\/healthcare-professionals\/\">Healthcare Professionals<\/a><\/li>\n<li id=\"menu-item-17235\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-17235\"><a target=\"_blank\" href=\"https:\/\/www.sialanar.co.uk\/\">Sialanar<sup>\u00ae<\/sup><\/a><\/li>\n<li id=\"menu-item-17236\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-17236\"><a target=\"_blank\" href=\"https:\/\/www.aqumeldi.co.uk\/\">Aqumeldi<sup>\u00ae<\/sup><\/a><\/li>\n<li id=\"menu-item-17234\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-17234\"><a href=\"https:\/\/www.proveca.com\/ga\/report-a-problem\/\">Report a problem<\/a><\/li>\n<\/ul><\/div><\/div><\/div><\/p><\/div><div class='flex_column_table av-4gehfcz-fc040a2826d966832fc8af08ea969a25 sc-av_one_third av-equal-height-column-flextable'><div  class='flex_column av-4gehfcz-fc040a2826d966832fc8af08ea969a25 av_one_third  avia-builder-el-10  el_after_av_one_third  el_before_av_one_third  hcp_prod hcp_prod_sialanar first flex_column_table_cell av-equal-height-column av-align-top  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3xaah7n-db3551483132cfba60432145e62d5133\">\n#top .av-special-heading.av-3xaah7n-db3551483132cfba60432145e62d5133{\npadding-bottom:0;\n}\nbody .av-special-heading.av-3xaah7n-db3551483132cfba60432145e62d5133 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-3xaah7n-db3551483132cfba60432145e62d5133 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-3xaah7n-db3551483132cfba60432145e62d5133 av-special-heading-h3 blockquote modern-quote  avia-builder-el-11  el_before_av_image  avia-builder-el-first '><div class='av-subheading av-subheading_above'><p>Neurology<\/p>\n<\/div><h3 class='av-special-heading-tag '  >Sialanar<sup>&reg;<\/sup> (400mcg\/ml glycopyrronium bromide equivalent to 320mcg\/ml glycopyrronium)<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3kfoo6b-c68a27154cc0f40a91f68222b888538f\">\n.avia-image-container.av-3kfoo6b-c68a27154cc0f40a91f68222b888538f img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-3kfoo6b-c68a27154cc0f40a91f68222b888538f .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-3kfoo6b-c68a27154cc0f40a91f68222b888538f av-styling- avia-align-center  avia-builder-el-12  el_after_av_heading  el_before_av_textblock '  ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image- avia-img-lazy-loading-not- avia_image ' src=\"https:\/\/www.staging.proveca.com\/wp-content\/uploads\/2024\/06\/sia-logo3.svg\" alt='' title=''   \/><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-2vxmzgj-b7e5107dfd97baec5511f6bab9135b31 '  ><div class='avia_textblock' ><p>Sialanar<sup>&reg;<\/sup> is indicated for the symptomatic treatment of severe sialorrhoea (chronic pathological drooling) in children and adolescents aged 3 years and older with chronic neurological disorders.<\/p>\n<\/div><\/section><br \/>\n<div  class='avia-buttonrow-wrap av-mk5i9myl-78f3f20b5529024d9ed858c0ff293a00 avia-buttonrow-center  avia-builder-el-14  el_after_av_textblock  avia-builder-el-last '>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mk5icq8s-844d0d67a4f8d614a81730a4e3f4c2f1\">\n#top #wrap_all .avia-button.av-mk5icq8s-844d0d67a4f8d614a81730a4e3f4c2f1{\nmargin-bottom:30px;\nmargin-right:15px;\nmargin-left:15px;\n}\n<\/style>\n<a href='\/wp-content\/uploads\/2022\/09\/Prescribing-Information-IE-Sialanar-September-2022.pdf'  class='avia-button av-mk5icq8s-844d0d67a4f8d614a81730a4e3f4c2f1 avia-icon_select-yes-right-icon avia-size-small avia-color-theme-color'  target=\"_blank\"  rel=\"noopener noreferrer\"  aria-label=\"Prescribing Information\"><span class='avia_iconbox_title' >Prescribing Information<\/span><span class='avia_button_icon avia_button_icon_right avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue875' data-av_iconfont='entypo-fontello' ><\/span><\/a>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mk5i9laj-ee18558ce9bd288cab8335fa26cafbc1\">\n#top #wrap_all .avia-button.av-mk5i9laj-ee18558ce9bd288cab8335fa26cafbc1{\nmargin-bottom:30px;\nmargin-right:15px;\nmargin-left:15px;\n}\n<\/style>\n<a href='https:\/\/www.sialanar.co.uk\/'  class='avia-button av-mk5i9laj-ee18558ce9bd288cab8335fa26cafbc1 avia-icon_select-yes-right-icon avia-size-small avia-color-theme-color'  target=\"_blank\"  rel=\"noopener noreferrer\"  aria-label=\"More Information\"><span class='avia_iconbox_title' >More Information<\/span><span class='avia_button_icon avia_button_icon_right avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue875' data-av_iconfont='entypo-fontello' ><\/span><\/a>\n<\/div><\/p><\/div><div class='av-flex-placeholder'><\/div><div  class='flex_column av-2iar36r-16e68dc3d0c0bcac2bd157896b88d7cb av_one_third  avia-builder-el-15  el_after_av_one_third  el_before_av_one_third  hcp_prod hcp_prod_aqumeldi flex_column_table_cell av-equal-height-column av-align-top  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1xy57b7-7d9c759c8d16c74bfd0c1fd5592be89d\">\n#top .av-special-heading.av-1xy57b7-7d9c759c8d16c74bfd0c1fd5592be89d{\npadding-bottom:0;\n}\nbody .av-special-heading.av-1xy57b7-7d9c759c8d16c74bfd0c1fd5592be89d .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-1xy57b7-7d9c759c8d16c74bfd0c1fd5592be89d .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-1xy57b7-7d9c759c8d16c74bfd0c1fd5592be89d av-special-heading-h3 blockquote modern-quote  avia-builder-el-16  el_before_av_image  avia-builder-el-first '><div class='av-subheading av-subheading_above'><p>Cardiology<\/p>\n<\/div><h3 class='av-special-heading-tag '  >Aqumeldi<sup>\u00ae<\/sup> (enalapril maleate) 0.25mg and 1mg orodispersible tablets<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1l63k6b-216d9ea2e1da5f7493d9b8f767cd413c\">\n.avia-image-container.av-1l63k6b-216d9ea2e1da5f7493d9b8f767cd413c img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-1l63k6b-216d9ea2e1da5f7493d9b8f767cd413c .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-1l63k6b-216d9ea2e1da5f7493d9b8f767cd413c av-styling- avia-align-center  avia-builder-el-17  el_after_av_heading  el_before_av_textblock '  ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image- avia-img-lazy-loading-not- avia_image ' src=\"https:\/\/www.staging.proveca.com\/wp-content\/uploads\/2024\/02\/Aqumeldi-UK-Logo-R.jpg\" alt='' title=''   \/><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-18srboj-e5e66658861327787189f5e096703c38 '  ><div class='avia_textblock' ><p>Aqumeldi<sup>\u00ae <\/sup>is indicated for the treatment of heart failure in children from birth to less than 18 years.<\/p>\n<\/div><\/section><br \/>\n<div  class='avia-buttonrow-wrap av-mk5i9wze-fb812394f7c2067112385fcf5fd07518 avia-buttonrow-center  avia-builder-el-19  el_after_av_textblock  avia-builder-el-last '>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2a1vdv-890e9ce12171aac23e723e255810301c\">\n#top #wrap_all .avia-button.av-2a1vdv-890e9ce12171aac23e723e255810301c{\nmargin-bottom:30px;\nmargin-right:15px;\nmargin-left:15px;\n}\n<\/style>\n<a href='\/products\/aqumeldi\/pi\/uk'  class='avia-button av-2a1vdv-890e9ce12171aac23e723e255810301c avia-icon_select-yes-right-icon avia-size-small avia-color-theme-color'  target=\"_blank\"  rel=\"noopener noreferrer\"  aria-label=\"Prescribing Information\"><span class='avia_iconbox_title' >Prescribing Information<\/span><span class='avia_button_icon avia_button_icon_right avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue875' data-av_iconfont='entypo-fontello' ><\/span><\/a>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-mk5i9w9x-490165a8e624078bca855a6ac52bc032\">\n#top #wrap_all .avia-button.av-mk5i9w9x-490165a8e624078bca855a6ac52bc032{\nmargin-bottom:30px;\nmargin-right:15px;\nmargin-left:15px;\n}\n<\/style>\n<a href='https:\/\/www.aqumeldi.co.uk\/'  class='avia-button av-mk5i9w9x-490165a8e624078bca855a6ac52bc032 avia-icon_select-yes-right-icon avia-size-small avia-color-theme-color'  target=\"_blank\"  rel=\"noopener noreferrer\"  aria-label=\"More Information\"><span class='avia_iconbox_title' >More Information<\/span><span class='avia_button_icon avia_button_icon_right avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue875' data-av_iconfont='entypo-fontello' ><\/span><\/a>\n<\/div><\/p><\/div><div class='av-flex-placeholder'><\/div><div  class='flex_column av-vv8hs3-c223169420f772feed0a2842ca70c945 av_one_third  avia-builder-el-20  el_after_av_one_third  avia-builder-el-last  flex_column_table_cell av-equal-height-column av-align-top  column-top-margin'     ><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_3'  class='avia-section av-1gutpks-1ad0b1709586569f1f857b8dd213cb5a main_color avia-section-default avia-no-border-styling  avia-builder-el-21  el_after_av_section  avia-builder-el-last  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-15843'><div class='entry-content-wrapper clearfix'>\n<section  class='av_textblock_section av-124tmv0-0c05c82e61d5b0279236d5554c062c1e '  ><div class='avia_textblock' ><p style=\"text-align: center;\"><strong>Please see information below to report adverse events in the Republic of Ireland<\/strong><\/p>\n<\/div><\/section>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-kp8m3g-3f41a7c5d56b988df523b28f4effe2a0\">\n.avia_message_box.av-kp8m3g-3f41a7c5d56b988df523b28f4effe2a0{\nbackground-color:#ffffff;\ncolor:#000000;\nborder-style:solid;\nborder-width:5px 5px 5px 5px;\nborder-color:#000000;\nbox-shadow:none;\n}\n.avia_message_box.av-kp8m3g-3f41a7c5d56b988df523b28f4effe2a0 .avia_message_box_icon.avia-svg-icon svg:first-child{\nfill:#000000;\nstroke:#000000;\n}\n<\/style>\n<div id='avia-messagebox-' class='avia_message_box av_notification av-kp8m3g-3f41a7c5d56b988df523b28f4effe2a0 avia-color-custom avia-size-normal avia-icon_select-no avia-border-  avia-builder-el-23  el_after_av_textblock  avia-builder-el-last  report_banner' ><div class=\"avia_message_box_content\"><p>Adverse events should be reported. Reporting forms and information can be found at: <a style=\"font-size: inherit; text-decoration: underline;\" href=\"https:\/\/www.hpra.ie\" target=\"_blanck\" rel=\"noopener\">www.hpra.ie<\/a>.<br \/>\nAdverse events should also be reported to Proveca Limited.<br \/>\nPhone: +44 333 200 1866 E-mail: <a style=\"font-size: inherit; text-decoration: underline;\" href=\"mailto:medinfo@proveca.com\">medinfo@proveca.com<\/a><\/p>\n<\/div><\/div>\n<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-15843","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Healthcare Professionals - Proveca<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Healthcare Professionals - Proveca\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.proveca.com\/ga\/healthcare-professionals\/\" \/>\n<meta property=\"og:site_name\" content=\"Proveca\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-14T08:51:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.proveca.com\\\/ga\\\/healthcare-professionals\\\/\",\"url\":\"https:\\\/\\\/www.proveca.com\\\/ga\\\/healthcare-professionals\\\/\",\"name\":\"Healthcare Professionals - Proveca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.proveca.com\\\/ga\\\/#website\"},\"datePublished\":\"2023-10-11T12:21:15+00:00\",\"dateModified\":\"2026-05-14T08:51:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.proveca.com\\\/ga\\\/healthcare-professionals\\\/#breadcrumb\"},\"inLanguage\":\"en-IE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.proveca.com\\\/ga\\\/healthcare-professionals\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.proveca.com\\\/ga\\\/healthcare-professionals\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.proveca.com\\\/ga\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Healthcare Professionals\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.proveca.com\\\/ga\\\/#website\",\"url\":\"https:\\\/\\\/www.proveca.com\\\/ga\\\/\",\"name\":\"Proveca\",\"description\":\"Medicines for children\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.proveca.com\\\/ga\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-IE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Healthcare Professionals - Proveca","robots":{"index":"noindex","follow":"follow"},"og_type":"article","og_title":"Healthcare Professionals - Proveca","og_url":"https:\/\/www.proveca.com\/ga\/healthcare-professionals\/","og_site_name":"Proveca","article_modified_time":"2026-05-14T08:51:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.proveca.com\/ga\/healthcare-professionals\/","url":"https:\/\/www.proveca.com\/ga\/healthcare-professionals\/","name":"Healthcare Professionals - Proveca","isPartOf":{"@id":"https:\/\/www.proveca.com\/ga\/#website"},"datePublished":"2023-10-11T12:21:15+00:00","dateModified":"2026-05-14T08:51:16+00:00","breadcrumb":{"@id":"https:\/\/www.proveca.com\/ga\/healthcare-professionals\/#breadcrumb"},"inLanguage":"en-IE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.proveca.com\/ga\/healthcare-professionals\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.proveca.com\/ga\/healthcare-professionals\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.proveca.com\/ga\/homepage\/"},{"@type":"ListItem","position":2,"name":"Healthcare Professionals"}]},{"@type":"WebSite","@id":"https:\/\/www.proveca.com\/ga\/#website","url":"https:\/\/www.proveca.com\/ga\/","name":"Proveca","description":"Medicines for children","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.proveca.com\/ga\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-IE"}]}},"_links":{"self":[{"href":"https:\/\/www.proveca.com\/ga\/wp-json\/wp\/v2\/pages\/15843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.proveca.com\/ga\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.proveca.com\/ga\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.proveca.com\/ga\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.proveca.com\/ga\/wp-json\/wp\/v2\/comments?post=15843"}],"version-history":[{"count":15,"href":"https:\/\/www.proveca.com\/ga\/wp-json\/wp\/v2\/pages\/15843\/revisions"}],"predecessor-version":[{"id":17232,"href":"https:\/\/www.proveca.com\/ga\/wp-json\/wp\/v2\/pages\/15843\/revisions\/17232"}],"wp:attachment":[{"href":"https:\/\/www.proveca.com\/ga\/wp-json\/wp\/v2\/media?parent=15843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}